{"id":2622,"date":"2022-09-12T22:23:10","date_gmt":"2022-09-12T20:23:10","guid":{"rendered":"https:\/\/www.triaderealestate.com\/wordpress\/?page_id=2622"},"modified":"2023-04-03T20:29:53","modified_gmt":"2023-04-03T18:29:53","slug":"lascia-la-tua-richiesta","status":"publish","type":"page","link":"https:\/\/www.triaderealestate.com\/wordpress\/lascia-la-tua-richiesta\/","title":{"rendered":"Invia la tua richiesta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Qualunque sia la tua esigenza immobiliare, lascia qui la tua richiesta spiegando le caratteristiche dell\u2019immobile che stai cercando, indicandoci i tuoi recapiti<\/p>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f627-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"627\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wordpress\/wp-json\/wp\/v2\/pages\/2622#wpcf7-f627-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"627\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f627-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/>\n<\/fieldset>\n<p>Il tuo nome (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>Il tuo cognome (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-659\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-659\" \/><\/span>\n<\/p>\n<p>Il tuo numero telefonico (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-13\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-13\" \/><\/span>\n<\/p>\n<p>La tua email (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<span class=\"wpcf7-form-control-wrap url-pagina-riferimento\" data-name=\"url-pagina-riferimento\"><input type=\"hidden\" name=\"url-pagina-riferimento\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.triaderealestate.com\/wordpress\/wordpress\/wp-json\/wp\/v2\/pages\/2622\"><\/span>\n<span class=\"wpcf7-form-control-wrap titolo-pagina-riferimento\" data-name=\"titolo-pagina-riferimento\"><input type=\"hidden\" name=\"titolo-pagina-riferimento\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Invia la tua richiesta\"><\/span>\n<p>Il tuo messaggio\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>Dichiaro di aver letto l'Informativa Privacy consultabile al link seguente <a href=\"https:\/\/www.triaderealestate.com\/wordpress\/privacy\/\">\"Informativa Privacy ex art. 13 del Regolamento europeo n. 679\/2016 (\u201cGDPR\u201d)\"<\/a> e, riguardo al trattamento dei miei dati personali, dichiaro che:\n<\/p>\n<p>Acconsento <span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-451\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-451\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Invia\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"174\"\/><script data-jetpack-boost=\"ignore\">\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Qualunque sia la tua esigenza immobiliare, lascia qui la tua richiesta spiegando le caratteristiche dell\u2019immobile che stai cercando, indicandoci i tuoi recapiti<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2622","page","type-page","status-publish","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/P4Ovph-Gi","jetpack-related-posts":[{"id":752,"url":"https:\/\/www.triaderealestate.com\/wordpress\/attivita-commerciali\/","url_meta":{"origin":2622,"position":0},"title":"Attivit\u00e0 Commerciali","author":"TriadeRealEstate","date":"15 Luglio 2016","format":false,"excerpt":"La Tua attivit\u00e0 comincia qui \u00a0 RICHIESTE\u00a0ATTIVIT\u00c0 COMMERCIALI Se stai cercando un\u2019 Attivit\u00e0 Commerciale compila il form sottostante lasciandoci la tua richiesta. Saremo lieti di ricontattarti per prospettarti l'offerta pi\u00f9 vicina alla tua esigenza!","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"Photo credits Finn Hackshaw","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/5B669F49-E46E-4F57-AD32-151E2D06CD21-scaled.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/5B669F49-E46E-4F57-AD32-151E2D06CD21-scaled.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/5B669F49-E46E-4F57-AD32-151E2D06CD21-scaled.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/5B669F49-E46E-4F57-AD32-151E2D06CD21-scaled.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/5B669F49-E46E-4F57-AD32-151E2D06CD21-scaled.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":445,"url":"https:\/\/www.triaderealestate.com\/wordpress\/immobili-per-limpresa\/","url_meta":{"origin":2622,"position":1},"title":"Immobili per l&#8217;Impresa","author":"TriadeRealEstate","date":"19 Maggio 2016","format":false,"excerpt":"La tua Impresa comincia qui LOCAZIONE https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-commerciale-locazione\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-studio-medico-locazione\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-commerciale-vendita\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-commerciale-vendita-2\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-vendita\/ RICHIESTE IMMOBILI COMMERCIALI Se stai cercando un immobile commerciale\u00a0in VENDITA o LOCAZIONE, compila il form sottostante lasciandoci la tua richiesta. Saremo lieti di ricontattarti per prospettarti l'offerta pi\u00f9 vicina alla tua esigenza!","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/01371C82-E9E7-40A4-91F6-23C14E7E1A43-scaled.jpeg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/01371C82-E9E7-40A4-91F6-23C14E7E1A43-scaled.jpeg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/01371C82-E9E7-40A4-91F6-23C14E7E1A43-scaled.jpeg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/01371C82-E9E7-40A4-91F6-23C14E7E1A43-scaled.jpeg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/01371C82-E9E7-40A4-91F6-23C14E7E1A43-scaled.jpeg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1060,"url":"https:\/\/www.triaderealestate.com\/wordpress\/building-lots\/","url_meta":{"origin":2622,"position":2},"title":"Suoli Edificabili","author":"TriadeRealEstate","date":"25 Gennaio 2017","format":false,"excerpt":"COMPRARE CON NOILe vostre richieste sono i nostri obiettivi! Qualunque sia l\u2019esigenza di acquisto dei nostri clienti, li accompagniamo con competenza e riservatezza nella ricerca e nella scelta del loro immobile, sino al rogito notarile. \u00a0 RICHIESTE SUOLI EDIFICABILI Se stai cercando un suolo edificabile non esitate a compilare il\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/88C22AD0-D1E1-4190-B051-727514BDC615-scaled.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/88C22AD0-D1E1-4190-B051-727514BDC615-scaled.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/88C22AD0-D1E1-4190-B051-727514BDC615-scaled.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/88C22AD0-D1E1-4190-B051-727514BDC615-scaled.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/88C22AD0-D1E1-4190-B051-727514BDC615-scaled.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2618,"url":"https:\/\/www.triaderealestate.com\/wordpress\/trova-immobile\/","url_meta":{"origin":2622,"position":3},"title":"Trova Immobile","author":"TriadeRealEstate","date":"12 Settembre 2022","format":false,"excerpt":"Immobili in Vendita Immobili in Affitto Terreni Agricoli Immobili per l\u2019impresa Attivit\u00e0 Commerciali Annunci su Cercacasa Inviaci la tua richiesta","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2479,"url":"https:\/\/www.triaderealestate.com\/wordpress\/vendi-con-noi\/","url_meta":{"origin":2622,"position":4},"title":"Vendi con noi","author":"TriadeRealEstate","date":"28 Luglio 2022","format":false,"excerpt":"Se vuoi vendere un immobile storico, nel centro della tua citt\u00e0, in campagna, una masseria, trulli o altri immobili tipici che conservano le tracce della tradizione delle nostre terre, non esitare a contattarci dopo una valutazione realistica della tua propriet\u00e0, lo porremo in vendita alle migliori condizioni di mercato. Contattaci\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/07\/F9224AE0-E590-4309-A737-D7C60F86F595-scaled.jpeg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/07\/F9224AE0-E590-4309-A737-D7C60F86F595-scaled.jpeg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/07\/F9224AE0-E590-4309-A737-D7C60F86F595-scaled.jpeg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/07\/F9224AE0-E590-4309-A737-D7C60F86F595-scaled.jpeg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/07\/F9224AE0-E590-4309-A737-D7C60F86F595-scaled.jpeg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4129,"url":"https:\/\/www.triaderealestate.com\/wordpress\/la-tua-proprieta-in-puglia\/","url_meta":{"origin":2622,"position":5},"title":"La tua propriet\u00e0 in Puglia","author":"TriadeRealEstate","date":"15 Ottobre 2025","format":false,"excerpt":"Immersa nel verde in uno scenario unico a pochi metri dalle maggiori vie di collegamento (autostrada, ecc.), in posizione sopraelevata e con panorama mozzafiato, proponiamo in vendita una propriet\u00e0 unica nel suo genere: Immobile di pregio in fase di ristrutturazione con annessi locali allo stato originario a servizio dei contadini\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_8205-scaled.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_8205-scaled.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_8205-scaled.jpeg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/10\/IMG_8205-scaled.jpeg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages\/2622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/comments?post=2622"}],"version-history":[{"count":4,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages\/2622\/revisions"}],"predecessor-version":[{"id":2856,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages\/2622\/revisions\/2856"}],"wp:attachment":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/media?parent=2622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}