{"id":2942,"date":"2023-08-01T14:07:08","date_gmt":"2023-08-01T12:07:08","guid":{"rendered":"https:\/\/www.triaderealestate.com\/wordpress\/?page_id=2942"},"modified":"2024-01-24T11:36:50","modified_gmt":"2024-01-24T10:36:50","slug":"palagiano-intero-stabile-vendita","status":"publish","type":"page","link":"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/","title":{"rendered":"Palagiano &#8211; Intero Stabile- Vendita"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>\u20ac 50.000,00<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Via Bellucci, a pochi passi dalla Piazza e dal centro cittadino, proponiamo in vendita:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Immobile indipendente con camino e lastrico solare e balconcini e con sottostante ampio deposito. Tre ingressi complessivi. Si tratta di un intero stabile indipendente, tipico del luogo, con le caratteristiche volte in tufo, da ristrutturare e con ampie potenzialit\u00e0 di trasformazione. L&#8217;abitazione ha una Classe energetica F &#8211; 182,45 KWh\/m2 anno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Vendita  \u20ac 50.000,00<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Per Informazioni:<\/strong> Vincenzo Pugliese <a href=\"tel.: +39 3926928212\">tel.: +39 3926928212<\/a> email:<a href=\"mailto:info@triaderealestate.com\">info@triaderealestate.com<\/a> Web: <a href=\"http:\/\/Www.triaderealestate.com\">www.triaderealestate.com<\/a> <em><strong>Per richiedere informazioni \u00e8 anche possibile compilare in ogni sua parte\u00a0il form sottostante e cliccare il pulsante di invio:<\/strong><\/em><\/p>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f627-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"627\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wordpress\/wp-json\/wp\/v2\/pages\/2942#wpcf7-f627-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"627\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f627-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/>\n<\/fieldset>\n<p>Il tuo nome (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>Il tuo cognome (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-659\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-659\" \/><\/span>\n<\/p>\n<p>Il tuo numero telefonico (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-13\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-13\" \/><\/span>\n<\/p>\n<p>La tua email (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<span class=\"wpcf7-form-control-wrap url-pagina-riferimento\" data-name=\"url-pagina-riferimento\"><input type=\"hidden\" name=\"url-pagina-riferimento\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.triaderealestate.com\/wordpress\/wordpress\/wp-json\/wp\/v2\/pages\/2942\"><\/span>\n<span class=\"wpcf7-form-control-wrap titolo-pagina-riferimento\" data-name=\"titolo-pagina-riferimento\"><input type=\"hidden\" name=\"titolo-pagina-riferimento\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Palagiano - Intero Stabile- Vendita\"><\/span>\n<p>Il tuo messaggio\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>Dichiaro di aver letto l'Informativa Privacy consultabile al link seguente <a href=\"https:\/\/www.triaderealestate.com\/wordpress\/privacy\/\">\"Informativa Privacy ex art. 13 del Regolamento europeo n. 679\/2016 (\u201cGDPR\u201d)\"<\/a> e, riguardo al trattamento dei miei dati personali, dichiaro che:\n<\/p>\n<p>Acconsento <span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-451\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-451\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Invia\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"62\"\/><script data-jetpack-boost=\"ignore\">\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"272\" data-attachment-id=\"3239\" data-permalink=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/aaa\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?fit=2560%2C1466&amp;ssl=1\" data-orig-size=\"2560,1466\" data-comments-opened=\"0\" data-image-title=\"aaa\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?fit=474%2C272&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa.jpg?resize=474%2C272&#038;ssl=1\" alt=\"\" class=\"wp-image-3239 size-full\" srcset=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?resize=1024%2C587&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?resize=300%2C172&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?resize=1536%2C880&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?resize=2048%2C1173&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?w=948&amp;ssl=1 948w, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/01\/aaa-scaled.jpg?w=1422&amp;ssl=1 1422w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\" style=\"font-size:12px\"><em><strong>Classe energetica F &#8211; <\/strong>182,45 KWh\/m<sup>2<\/sup> anno<\/em><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f627-o2\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"627\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wordpress\/wp-json\/wp\/v2\/pages\/2942#wpcf7-f627-o2\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"627\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f627-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/>\n<\/fieldset>\n<p>Il tuo nome (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>Il tuo cognome (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-659\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-659\" \/><\/span>\n<\/p>\n<p>Il tuo numero telefonico (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-13\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-13\" \/><\/span>\n<\/p>\n<p>La tua email (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<span class=\"wpcf7-form-control-wrap url-pagina-riferimento\" data-name=\"url-pagina-riferimento\"><input type=\"hidden\" name=\"url-pagina-riferimento\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.triaderealestate.com\/wordpress\/wordpress\/wp-json\/wp\/v2\/pages\/2942\"><\/span>\n<span class=\"wpcf7-form-control-wrap titolo-pagina-riferimento\" data-name=\"titolo-pagina-riferimento\"><input type=\"hidden\" name=\"titolo-pagina-riferimento\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Palagiano - Intero Stabile- Vendita\"><\/span>\n<p>Il tuo messaggio\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>Dichiaro di aver letto l'Informativa Privacy consultabile al link seguente <a href=\"https:\/\/www.triaderealestate.com\/wordpress\/privacy\/\">\"Informativa Privacy ex art. 13 del Regolamento europeo n. 679\/2016 (\u201cGDPR\u201d)\"<\/a> e, riguardo al trattamento dei miei dati personali, dichiaro che:\n<\/p>\n<p>Acconsento <span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-451\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-451\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Invia\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_2\" name=\"_wpcf7_ak_js\" value=\"171\"\/><script data-jetpack-boost=\"ignore\">\ndocument.getElementById( \"ak_js_2\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:36.05928%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2950\" data-permalink=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/img_9021\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9021-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"0\" data-image-title=\"IMG_9021\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9021-scaled.jpeg?fit=474%2C632&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Apri immagine 1 di 6 a schermo intero\" srcset=\"https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9021-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9021-768x1024.jpeg?strip=info&#038;w=768&#038;ssl=1 768w\" alt=\"\" data-height=\"2560\" data-id=\"2950\" data-link=\"https:\/\/www.triaderealestate.com\/wordpress\/?attachment_id=2950\" data-url=\"https:\/\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9021-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9021-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:63.94072%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2949\" data-permalink=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/img_9019\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9019-scaled.jpeg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-title=\"IMG_9019\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9019-scaled.jpeg?fit=474%2C356&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Apri immagine 2 di 6 a schermo intero\" srcset=\"https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9019-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9019-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9019-1024x768.jpeg?strip=info&#038;w=1024&#038;ssl=1 1024w\" alt=\"\" data-height=\"1920\" data-id=\"2949\" data-link=\"https:\/\/www.triaderealestate.com\/wordpress\/?attachment_id=2949\" data-url=\"https:\/\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9019-1024x768.jpeg\" data-width=\"2560\" src=\"https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9019-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:34.79009%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2948\" data-permalink=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/img_9018\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9018-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"0\" data-image-title=\"IMG_9018\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9018-scaled.jpeg?fit=474%2C632&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Apri immagine 3 di 6 a schermo intero\" srcset=\"https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9018-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9018-768x1024.jpeg?strip=info&#038;w=768&#038;ssl=1 768w\" alt=\"\" data-height=\"2560\" data-id=\"2948\" data-link=\"https:\/\/www.triaderealestate.com\/wordpress\/?attachment_id=2948\" data-url=\"https:\/\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9018-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9018-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:30.41982%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2947\" data-permalink=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/img_9017\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9017-scaled.jpeg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-title=\"IMG_9017\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9017-scaled.jpeg?fit=474%2C356&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Apri immagine 4 di 6 a schermo intero\" srcset=\"https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9017-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9017-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9017-1024x768.jpeg?strip=info&#038;w=1024&#038;ssl=1 1024w\" alt=\"\" data-height=\"1920\" data-id=\"2947\" data-link=\"https:\/\/www.triaderealestate.com\/wordpress\/?attachment_id=2947\" data-url=\"https:\/\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9017-1024x768.jpeg\" data-width=\"2560\" src=\"https:\/\/i1.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9017-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2946\" data-permalink=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/img_9016\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9016-scaled.jpeg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-title=\"IMG_9016\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9016-scaled.jpeg?fit=474%2C356&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Apri immagine 5 di 6 a schermo intero\" srcset=\"https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9016-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9016-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9016-1024x768.jpeg?strip=info&#038;w=1024&#038;ssl=1 1024w\" alt=\"\" data-height=\"1920\" data-id=\"2946\" data-link=\"https:\/\/www.triaderealestate.com\/wordpress\/?attachment_id=2946\" data-url=\"https:\/\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9016-1024x768.jpeg\" data-width=\"2560\" src=\"https:\/\/i2.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9016-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:34.79009%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2945\" data-permalink=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/img_9015\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9015-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"0\" data-image-title=\"IMG_9015\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9015-scaled.jpeg?fit=474%2C632&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Apri immagine 6 di 6 a schermo intero\" srcset=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9015-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9015-768x1024.jpeg?strip=info&#038;w=768&#038;ssl=1 768w\" alt=\"\" data-height=\"2560\" data-id=\"2945\" data-link=\"https:\/\/www.triaderealestate.com\/wordpress\/?attachment_id=2945\" data-url=\"https:\/\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9015-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2023\/08\/IMG_9015-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"474\" height=\"267\" src=\"https:\/\/www.youtube.com\/embed\/GcO5G7cf8uM?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=it-IT&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><em><sub>Nota: tutte le informazioni qui presenti non costituiscono elemento contrattuale e non possiamo garantirne la precisione o la completezza ed andranno considerate di conseguenza. Si declina ogni responsabilit\u00e0 da errori, omissioni, imprecisioni cui potrebbero essere soggette le proposte pubblicitarie e da ritiro senza preavviso. Poich\u00e9 le dimensioni e le caratteristiche indicate sono approssimative e non verificate, si consiglia di incaricare un proprio tecnico di fiducia per verificarne la correttezza.<\/sub><\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>\u20ac 50.000,00 In Via Bellucci, a pochi passi dalla Piazza e dal centro cittadino, proponiamo in vendita: Immobile indipendente con camino e lastrico solare e balconcini e con sottostante ampio deposito. Tre ingressi complessivi. Si tratta di un intero stabile indipendente, tipico del luogo, con le caratteristiche volte in tufo, da ristrutturare e con ampie &hellip; <a href=\"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita\/\" class=\"more-link\">Continua la lettura di <span class=\"screen-reader-text\">Palagiano &#8211; Intero Stabile- Vendita<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2948,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2942","page","type-page","status-publish","has-post-thumbnail","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/P4Ovph-Ls","jetpack-related-posts":[{"id":52,"url":"https:\/\/www.triaderealestate.com\/wordpress\/immobili\/","url_meta":{"origin":2942,"position":0},"title":"IMMOBILI IN VENDITA","author":"TriadeRealEstate","date":"26 Luglio 2014","format":false,"excerpt":"COMPRARE CON NOILe vostre richieste sono i nostri obiettivi! \"Qualunque sia l\u2019esigenza di acquisto e di vendita dei nostri clienti, li accompagniamo con competenza e riservatezza nella ricerca e nella scelta del loro immobile, sino al rogito notarile.\" https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-vendita-2\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita-4\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-abitazione-e-rustico-vendita\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-appartamento-vendita-3\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-vendita\/ https:\/\/www.triaderealestate.com\/wordpress\/mottola-appartamento-vendita\/ https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita-7 https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-commerciale-vendita-2 https:\/\/www.triaderealestate.com\/wordpress\/palagiano-deposito-vendita https:\/\/www.triaderealestate.com\/wordpress\/palagiano-autorimessa-vendita\/?fbclid=IwZXh0bgNhZW0CMTEAAR2sfFs6bC2kIT0Ve6RkEt_AL7bkyqsxeCO66Nbawm9Lhjs4iL6pCKKziNA_aem_AdDotnHaY5-s2_54GpvRMVmi25STIdyyinLbdVpouJ6-YJ2pLte_WzKmxzi3hh7AEDBoBbVB_LqlL2ExNbx9Xnh1 https:\/\/www.triaderealestate.com\/wordpress\/palagiano-appartamento-garage-e-deposito https:\/\/www.triaderealestate.com\/wordpress\/palagiano-locale-commerciale-vendita\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/06\/724E7222-4701-477B-ADD9-E6A6BF3B3789-scaled.jpeg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/06\/724E7222-4701-477B-ADD9-E6A6BF3B3789-scaled.jpeg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/06\/724E7222-4701-477B-ADD9-E6A6BF3B3789-scaled.jpeg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/06\/724E7222-4701-477B-ADD9-E6A6BF3B3789-scaled.jpeg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/06\/724E7222-4701-477B-ADD9-E6A6BF3B3789-scaled.jpeg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1735,"url":"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita-3\/","url_meta":{"origin":2942,"position":1},"title":"Palagiano &#8211; Intero Stabile &#8211; Vendita","author":"TriadeRealEstate","date":"28 Ottobre 2020","format":false,"excerpt":"\u20ac 65.000,00 In via Imbriani ed in Via Paisiello, in posizione angolare, \u00a0a pochi metri da Corso Lenne, proponiamo in vendita un intero stabile: abitazione al piano primo composta di 2 vani catastali, balcone, \u00a0e terrazzo; locale garage al piano terra di circa 42 mq catastali. L'immobile si presenta un\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"vista esterno","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2020\/10\/IMG_4949-scaled.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2020\/10\/IMG_4949-scaled.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2020\/10\/IMG_4949-scaled.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2020\/10\/IMG_4949-scaled.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3783,"url":"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita-7\/","url_meta":{"origin":2942,"position":2},"title":"Palagiano &#8211; Intero Stabile &#8211; Vendita","author":"TriadeRealEstate","date":"17 Luglio 2024","format":false,"excerpt":"Vendita - \u20ac 295.000,00 A Palagiano, in Via San Francesco d'Assisi, in posizione riservata e ben collegata, a pochi metri da Via Quasimodo e da Viale Chiatona, proponiamo in vendita: INTERO STABILE Al piano terra troviamo due unit\u00e0 immobiliari: Abitazione con veranda e giardino con accesso indipendente. 6,5 vani catastali\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/IMG_4171-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/IMG_4171-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/IMG_4171-scaled.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/IMG_4171-scaled.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/IMG_4171-scaled.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4033,"url":"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita-4\/","url_meta":{"origin":2942,"position":3},"title":"Palagiano &#8211; Intero Stabile &#8211; Vendita","author":"TriadeRealEstate","date":"12 Marzo 2025","format":false,"excerpt":"Vendita - \u20ac 180.000,00 Palagiano , Viale Chiatona: Proponiamo in Vendita un intero stabile, da rifinire\/ristrutturare, cos\u00ec composto: Piano Terra: due immobili accatastati a deposito, della superficie catastale totale complessiva di circa 136 m2. Ognuno di questi due immobili ha un accesso da Viale Chiatona tramite saracinesca ed un accesso\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/03\/vle-chiatona.jpg?fit=708%2C529&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/03\/vle-chiatona.jpg?fit=708%2C529&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/03\/vle-chiatona.jpg?fit=708%2C529&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2025\/03\/vle-chiatona.jpg?fit=708%2C529&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2597,"url":"https:\/\/www.triaderealestate.com\/wordpress\/palagiano-intero-stabile-vendita-5\/","url_meta":{"origin":2942,"position":4},"title":"Palagiano &#8211; Intero Stabile- Vendita","author":"TriadeRealEstate","date":"6 Settembre 2022","format":false,"excerpt":"\u20ac 350.000,00 In prossimit\u00e0 di Viale Chiatona, a pochi metri dalla Guardia Medica Palagiano, proponiamo un vendita un intero stabile cos\u00ec composto: Al piano seminterrato: autorimessa della superficie catastale totale di 183 m2 ; Al piano terra vi \u00e8 , da un ampio giardino circostante, l\u2019 accesso al portone di\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/775609BE-76A8-45C0-900F-6DA017024D57-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/775609BE-76A8-45C0-900F-6DA017024D57-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/775609BE-76A8-45C0-900F-6DA017024D57-scaled.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/775609BE-76A8-45C0-900F-6DA017024D57-scaled.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2022\/08\/775609BE-76A8-45C0-900F-6DA017024D57-scaled.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3853,"url":"https:\/\/www.triaderealestate.com\/wordpress\/mottola-appartamento-vendita\/","url_meta":{"origin":2942,"position":5},"title":"Mottola &#8211; Appartamento &#8211; VENDITA","author":"TriadeRealEstate","date":"31 Luglio 2024","format":false,"excerpt":"Vendita - \u20ac 50.000,00 Posizione: Mottola - In Via Guglielmo Marconi, al piano II, proponiamo in vendita: Descrizione: Appartamento di circa 89 m2 catastali totali, con due balconi di cui uno ampio angolare su via Risorgimento ed affacci panoramici, composto da ingresso, corridoio, cucina abitabile, bagno , due ampie camere.\u2026","rel":"","context":"Articolo simile","block_context":{"text":"Articolo simile","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/img_4366.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/img_4366.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/img_4366.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/img_4366.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.triaderealestate.com\/wordpress\/wp-content\/uploads\/2024\/07\/img_4366.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages\/2942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/comments?post=2942"}],"version-history":[{"count":5,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages\/2942\/revisions"}],"predecessor-version":[{"id":3240,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/pages\/2942\/revisions\/3240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/media\/2948"}],"wp:attachment":[{"href":"https:\/\/www.triaderealestate.com\/wordpress\/wp-json\/wp\/v2\/media?parent=2942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}